{"id":55,"date":"2025-10-15T09:52:04","date_gmt":"2025-10-15T07:52:04","guid":{"rendered":"https:\/\/alexandravassileva.com\/?page_id=55"},"modified":"2026-06-25T22:52:22","modified_gmt":"2026-06-25T20:52:22","slug":"biographie","status":"publish","type":"page","link":"https:\/\/alexandravassileva.com\/index.php\/biographie\/","title":{"rendered":"Biographie"},"content":{"rendered":"\n<p class=\"has-small-font-size wp-block-paragraph\" style=\"margin-top:0;margin-bottom:0\"><strong>Alexandra Vassileva<\/strong>, n\u00e9e en <strong>2012<\/strong>, d\u00e9couvre le piano \u00e0 l\u2019\u00e2ge de <strong>cinq ans<\/strong>. Depuis son entr\u00e9e au <strong>Conservatoire de la Ville de Luxembourg en 2018<\/strong>, elle cultive une passion profonde pour son instrument, port\u00e9e par une discipline remarquable et une sensibilit\u00e9 musicale d\u00e9j\u00e0 tr\u00e8s affirm\u00e9e.<br><br>Son parcours est jalonn\u00e9 de nombreuses distinctions : plusieurs <strong>premiers prix<\/strong> au concours <strong>Golden Keys<\/strong> du Conservatoire du Luxembourg entre <strong>2020 et 2026<\/strong>, ainsi que <strong>deux m\u00e9dailles d\u2019or<\/strong> au concours de piano de l\u2019<strong>UGDA<\/strong>. Elle s\u2019illustre \u00e9galement \u00e0 l\u2019\u00e9tranger, remportant <strong>deux premiers prix<\/strong> (cat\u00e9gories A et B) au concours de piano de <strong>Li\u00e8ge (Belgique)<\/strong> et un <strong>Deuxi\u00e8me Prix<\/strong> au <strong>11\u1d49 concours pour jeunes pianistes de la R\u00e9gion SaarLorLux<\/strong>, organis\u00e9 au Mus\u00e9e de la Cath\u00e9drale de Tr\u00e8ves.<br><br>Alexandra a d\u00e9j\u00e0 eu l\u2019occasion de se produire <strong>\u00e0 trois reprises en soliste avec orchestre<\/strong>, des exp\u00e9riences d\u00e9terminantes qui ont renforc\u00e9 son ambition de poursuivre une carri\u00e8re musicale.<br><br>En 2025, elle obtient son <strong>dipl\u00f4me du Premier Prix au Conservatoire de la Ville de Luxembourg<\/strong>, avec la mention <strong>Grande Distinction<\/strong>. L\u2019un des moments les plus marquants de cette ann\u00e9e est sa prestation en <strong>octobre 2025<\/strong> sur la sc\u00e8ne de la <strong>Grande Salle de la Philharmonie de Luxembourg<\/strong>, lors de la c\u00e9r\u00e9monie officielle de remise des dipl\u00f4mes du Conservatoire.<br><br>Depuis <strong>2025<\/strong>, Alexandra est membre de la <strong>Young Talents Academy (YTA)<\/strong> du Conservatoire de la Ville de Luxembourg.<br><br>En <strong>2026<\/strong>, elle re\u00e7oit \u00e9galement un <strong>Premier Prix<\/strong> au concours de traduction organis\u00e9 par l\u2019<strong>Universit\u00e9 de Veliko Tarnovo<\/strong>, pour une traduction du bulgare vers le fran\u00e7ais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"731\" height=\"1024\" src=\"http:\/\/alexandravassileva.com\/wp-content\/uploads\/2025\/10\/Picture1-2-731x1024.png\" alt=\"Alexandra Vassileva - Jeune pianiste\" class=\"wp-image-87\" srcset=\"https:\/\/alexandravassileva.com\/wp-content\/uploads\/2025\/10\/Picture1-2-731x1024.png 731w, https:\/\/alexandravassileva.com\/wp-content\/uploads\/2025\/10\/Picture1-2-214x300.png 214w, https:\/\/alexandravassileva.com\/wp-content\/uploads\/2025\/10\/Picture1-2-768x1076.png 768w, https:\/\/alexandravassileva.com\/wp-content\/uploads\/2025\/10\/Picture1-2-1096x1536.png 1096w, https:\/\/alexandravassileva.com\/wp-content\/uploads\/2025\/10\/Picture1-2.png 1280w\" sizes=\"auto, (max-width: 731px) 100vw, 731px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Alexandra Vassileva, n\u00e9e en 2012, d\u00e9couvre le piano \u00e0 l\u2019\u00e2ge de cinq ans. Depuis son entr\u00e9e au Conservatoire de la Ville de Luxembourg en 2018, elle cultive une passion profonde pour son instrument, port\u00e9e par une discipline remarquable et une sensibilit\u00e9 musicale d\u00e9j\u00e0 tr\u00e8s affirm\u00e9e. Son parcours est jalonn\u00e9 de nombreuses distinctions : plusieurs premiers [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":156,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-55","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/alexandravassileva.com\/index.php\/wp-json\/wp\/v2\/pages\/55","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alexandravassileva.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alexandravassileva.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alexandravassileva.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/alexandravassileva.com\/index.php\/wp-json\/wp\/v2\/comments?post=55"}],"version-history":[{"count":17,"href":"https:\/\/alexandravassileva.com\/index.php\/wp-json\/wp\/v2\/pages\/55\/revisions"}],"predecessor-version":[{"id":265,"href":"https:\/\/alexandravassileva.com\/index.php\/wp-json\/wp\/v2\/pages\/55\/revisions\/265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alexandravassileva.com\/index.php\/wp-json\/wp\/v2\/media\/156"}],"wp:attachment":[{"href":"https:\/\/alexandravassileva.com\/index.php\/wp-json\/wp\/v2\/media?parent=55"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}